{"id":10967,"date":"2018-07-05T10:30:29","date_gmt":"2018-07-05T10:30:29","guid":{"rendered":"https:\/\/www.cuerdasvalero.com\/producto\/reinforced-polyester-braided-cord\/"},"modified":"2018-07-05T10:30:29","modified_gmt":"2018-07-05T10:30:29","slug":"reinforced-polyester-braided-cord","status":"publish","type":"product","link":"https:\/\/www.cuerdasvalero.com\/en\/producto\/reinforced-polyester-braided-cord\/","title":{"rendered":"Reinforced polyester braided cord"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>100% polyester braided cord on the outside with a nylon monofilament core, it has a diameter of 5 m\/m and is presented in rolls of 200 metres, in plain white or with distinctive colours, we have green, red and blue.<\/p>\n<p>These polyester ropes are highly resistant to friction and traction, resistant to ultraviolet rays, perfect to withstand inclement weather and to be outdoors. They withstand a high load as their core has little elasticity.<\/p>\n<p>Suitable for use in clotheslines, camping and lashing of goods.<\/p>\n","protected":false},"featured_media":11309,"template":"","meta":[],"product_brand":[],"product_cat":[581],"product_tag":[],"class_list":{"0":"post-10967","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-polyester-ropes","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reinforced polyester braided cord - Cuerdas Valero<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cuerdasvalero.com\/en\/producto\/reinforced-polyester-braided-cord\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reinforced polyester braided cord - Cuerdas Valero\" \/>\n<meta property=\"og:description\" content=\"100% polyester braided cord on the outside with a nylon monofilament core, it has a diameter of 5 m\/m and is presented in rolls of 200 metres, in plain white or with distinctive colours, we have green, red and blue.  These polyester ropes are highly resistant to friction and traction, resistant to ultraviolet rays, perfect to withstand inclement weather and to be outdoors. They withstand a high load as their core has little elasticity.  Suitable for use in clotheslines, camping and lashing of goods.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cuerdasvalero.com\/en\/producto\/reinforced-polyester-braided-cord\/\" \/>\n<meta property=\"og:site_name\" content=\"Cuerdas Valero\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CuerdasValero\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cuerdasvalero.com\/wp-content\/uploads\/2018\/07\/reforzado2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1452\" \/>\n\t<meta property=\"og:image:height\" content=\"912\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cuerdasvalero.com\\\/en\\\/producto\\\/reinforced-polyester-braided-cord\\\/\",\"url\":\"https:\\\/\\\/www.cuerdasvalero.com\\\/en\\\/producto\\\/reinforced-polyester-braided-cord\\\/\",\"name\":\"Reinforced polyester braided cord - Cuerdas Valero\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cuerdasvalero.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cuerdasvalero.com\\\/en\\\/producto\\\/reinforced-polyester-braided-cord\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cuerdasvalero.com\\\/en\\\/producto\\\/reinforced-polyester-braided-cord\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cuerdasvalero.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/Poliester-reforzado-bco-rojo.jpg\",\"datePublished\":\"2018-07-05T10:30:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cuerdasvalero.com\\\/en\\\/producto\\\/reinforced-polyester-braided-cord\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cuerdasvalero.com\\\/en\\\/producto\\\/reinforced-polyester-braided-cord\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.cuerdasvalero.com\\\/en\\\/producto\\\/reinforced-polyester-braided-cord\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cuerdasvalero.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/Poliester-reforzado-bco-rojo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cuerdasvalero.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/Poliester-reforzado-bco-rojo.jpg\",\"width\":2307,\"height\":1878},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cuerdasvalero.com\\\/en\\\/producto\\\/reinforced-polyester-braided-cord\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.cuerdasvalero.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/www.cuerdasvalero.com\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Reinforced polyester braided cord\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cuerdasvalero.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.cuerdasvalero.com\\\/en\\\/\",\"name\":\"Cuerdas Valero\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cuerdasvalero.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cuerdasvalero.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cuerdasvalero.com\\\/en\\\/#organization\",\"name\":\"Cuerdas Valero\",\"url\":\"https:\\\/\\\/www.cuerdasvalero.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.cuerdasvalero.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cuerdasvalero.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/cuerdas-valero-logo-.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cuerdasvalero.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/cuerdas-valero-logo-.jpg\",\"width\":196,\"height\":139,\"caption\":\"Cuerdas Valero\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cuerdasvalero.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CuerdasValero\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reinforced polyester braided cord - Cuerdas Valero","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cuerdasvalero.com\/en\/producto\/reinforced-polyester-braided-cord\/","og_locale":"en_US","og_type":"article","og_title":"Reinforced polyester braided cord - Cuerdas Valero","og_description":"100% polyester braided cord on the outside with a nylon monofilament core, it has a diameter of 5 m\/m and is presented in rolls of 200 metres, in plain white or with distinctive colours, we have green, red and blue.  These polyester ropes are highly resistant to friction and traction, resistant to ultraviolet rays, perfect to withstand inclement weather and to be outdoors. They withstand a high load as their core has little elasticity.  Suitable for use in clotheslines, camping and lashing of goods.","og_url":"https:\/\/www.cuerdasvalero.com\/en\/producto\/reinforced-polyester-braided-cord\/","og_site_name":"Cuerdas Valero","article_publisher":"https:\/\/www.facebook.com\/CuerdasValero\/","og_image":[{"width":1452,"height":912,"url":"https:\/\/www.cuerdasvalero.com\/wp-content\/uploads\/2018\/07\/reforzado2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cuerdasvalero.com\/en\/producto\/reinforced-polyester-braided-cord\/","url":"https:\/\/www.cuerdasvalero.com\/en\/producto\/reinforced-polyester-braided-cord\/","name":"Reinforced polyester braided cord - Cuerdas Valero","isPartOf":{"@id":"https:\/\/www.cuerdasvalero.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cuerdasvalero.com\/en\/producto\/reinforced-polyester-braided-cord\/#primaryimage"},"image":{"@id":"https:\/\/www.cuerdasvalero.com\/en\/producto\/reinforced-polyester-braided-cord\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cuerdasvalero.com\/wp-content\/uploads\/2018\/07\/Poliester-reforzado-bco-rojo.jpg","datePublished":"2018-07-05T10:30:29+00:00","breadcrumb":{"@id":"https:\/\/www.cuerdasvalero.com\/en\/producto\/reinforced-polyester-braided-cord\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cuerdasvalero.com\/en\/producto\/reinforced-polyester-braided-cord\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.cuerdasvalero.com\/en\/producto\/reinforced-polyester-braided-cord\/#primaryimage","url":"https:\/\/www.cuerdasvalero.com\/wp-content\/uploads\/2018\/07\/Poliester-reforzado-bco-rojo.jpg","contentUrl":"https:\/\/www.cuerdasvalero.com\/wp-content\/uploads\/2018\/07\/Poliester-reforzado-bco-rojo.jpg","width":2307,"height":1878},{"@type":"BreadcrumbList","@id":"https:\/\/www.cuerdasvalero.com\/en\/producto\/reinforced-polyester-braided-cord\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.cuerdasvalero.com\/en\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/www.cuerdasvalero.com\/tienda\/"},{"@type":"ListItem","position":3,"name":"Reinforced polyester braided cord"}]},{"@type":"WebSite","@id":"https:\/\/www.cuerdasvalero.com\/en\/#website","url":"https:\/\/www.cuerdasvalero.com\/en\/","name":"Cuerdas Valero","description":"","publisher":{"@id":"https:\/\/www.cuerdasvalero.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cuerdasvalero.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.cuerdasvalero.com\/en\/#organization","name":"Cuerdas Valero","url":"https:\/\/www.cuerdasvalero.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.cuerdasvalero.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.cuerdasvalero.com\/wp-content\/uploads\/2020\/04\/cuerdas-valero-logo-.jpg","contentUrl":"https:\/\/www.cuerdasvalero.com\/wp-content\/uploads\/2020\/04\/cuerdas-valero-logo-.jpg","width":196,"height":139,"caption":"Cuerdas Valero"},"image":{"@id":"https:\/\/www.cuerdasvalero.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CuerdasValero\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.cuerdasvalero.com\/en\/wp-json\/wp\/v2\/product\/10967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cuerdasvalero.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.cuerdasvalero.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cuerdasvalero.com\/en\/wp-json\/wp\/v2\/media\/11309"}],"wp:attachment":[{"href":"https:\/\/www.cuerdasvalero.com\/en\/wp-json\/wp\/v2\/media?parent=10967"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.cuerdasvalero.com\/en\/wp-json\/wp\/v2\/product_brand?post=10967"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.cuerdasvalero.com\/en\/wp-json\/wp\/v2\/product_cat?post=10967"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.cuerdasvalero.com\/en\/wp-json\/wp\/v2\/product_tag?post=10967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}